{"id":1325,"date":"2020-05-07T13:50:06","date_gmt":"2020-05-07T16:50:06","guid":{"rendered":"https:\/\/hdbsystems.com.br\/?p=1325"},"modified":"2020-05-07T13:50:06","modified_gmt":"2020-05-07T16:50:06","slug":"inteligencia-artificial-contra-o-covid-19","status":"publish","type":"post","link":"https:\/\/hdbsystems.com.br\/index.php\/2020\/05\/07\/inteligencia-artificial-contra-o-covid-19\/","title":{"rendered":"Intelig\u00eancia Artificial contra o COVID-19"},"content":{"rendered":"\n<p>Uma pesquisa da <a href=\"https:\/\/www.gartner.com\/en\/newsroom\/press-releases\/2020-05-06-gartner-identifies-nine-trends-for-hr-leaders-that-wi\">Gartner Inc<\/a>. apresentou as cinco \u00e1reas em que a <a href=\"https:\/\/hdbsystems.com.br\/index.php\/blog\/\">Intelig\u00eancia Artificial<\/a> mais beneficia e facilita as tomadas de decis\u00f5es para CIOs do Governo e da Sa\u00fade durante a pandemia. Segundo a an\u00e1lise, os recursos de IA s\u00e3o mais eficazes com a colabora\u00e7\u00e3o entre as equipes de TI e m\u00e9dicos especialistas em epidemias.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.gartner.com\/en\/newsroom\/press-releases\/2020-05-06-gartner-identifies-nine-trends-for-hr-leaders-that-wi\">Reportagem<\/a> de <strong>Katie Costello<\/strong> e <strong>Meghan Rimol<\/strong><\/p>\n\n\n\n<p>Executivos respons\u00e1veis \u200b\u200bpela estrat\u00e9gia de Intelig\u00eancia Artificial (IA), como CIOs e CDOs em organiza\u00e7\u00f5es governamentais e de sa\u00fade, devem aproveitar a IA em cinco \u00e1reas principais para melhorar a tomada de decis\u00f5es durante a pandemia de coronav\u00edrus.<\/p>\n\n\n\n<p>&#8220;Na luta contra o COVID-19, a IA oferece um importante arsenal de armas&#8221;, disse&nbsp;<a href=\"https:\/\/www.gartner.com\/analyst\/73800\">Erick Brethenoux,<\/a>&nbsp;vice-presidente de pesquisa da Gartner.&nbsp;\u201cEle permite que sejam feitas previs\u00f5es sobre a dissemina\u00e7\u00e3o do v\u00edrus, ajuda a diagnosticar casos com mais rapidez e precis\u00e3o, mede a efic\u00e1cia das contramedidas para retardar a dissemina\u00e7\u00e3o e otimiza os recursos de emerg\u00eancia, entre outros.&nbsp;O poder da IA \u200b\u200bn\u00e3o deve ser ignorado ou apenas parcialmente alavancado, desde que seja aplicado de maneira&nbsp;<a href=\"https:\/\/www.gartner.com\/smarterwithgartner\/3-actions-for-ethical-data-collection-during-pandemics\/\">eticamente<\/a>&nbsp;respons\u00e1vel. \u201d<\/p>\n\n\n\n<p>As cinco \u00e1reas em que o uso da Intelig\u00eancia artificial \u200b\u200bpara combater o COVID-19 s\u00e3o a <strong>detec\u00e7\u00e3o precoce<\/strong> e <strong>an\u00e1lise epid\u00eamica<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Intelig\u00eancia Artificial para entender, analisar e prever a expans\u00e3o do v\u00edrus<\/h3>\n\n\n\n<p>O rastreamento automatizado de contatos, \u00e9 usado para criar gr\u00e1ficos detalhados de intera\u00e7\u00e3o social. Dessa forma \u00e9 feita a an\u00e1lise de uma infinidade de dados de cidad\u00e3os, como localiza\u00e7\u00f5es de telefones celulares e reconhecimento facial p\u00fablico. A partir dessa an\u00e1lise \u00e9 poss\u00edvel retroceder o movimento de pessoas para identificar a prov\u00e1vel fonte de v\u00edrus.&nbsp;Os indiv\u00edduos que encontraram a fonte podem ser notificados, testados ou colocados em quarentena.<\/p>\n\n\n\n<p>\u201cOutras aplica\u00e7\u00f5es de IA que se enquadram nessa \u00e1rea incluem previs\u00e3o de epidemias e monitoramento do desenvolvimento da imunidade do rebanho.&nbsp;Tais recursos s\u00e3o obviamente altamente relevantes a curto prazo, \u00e0 medida que a sociedade tenta &#8216;achatar a curva&#8217; e minimizar a carga sobre nossos sistemas de sa\u00fade, mas tamb\u00e9m s\u00e3o importantes a longo prazo se novos surtos, esperan\u00e7osamente menores, reaparecerem \u201d, disse o Sr. Brethenoux.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conten\u00e7\u00e3o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/h4>\n\n\n\n<p>Considerando o enorme impacto social e econ\u00f4mico de medidas &#8220;uniformes para todos&#8221;, a colabora\u00e7\u00e3o com especialistas que n\u00e3o s\u00e3o de TI \u00e9 fundamental ao aplicar a IA aos esfor\u00e7os de conten\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;A an\u00e1lise do comportamento obt\u00e9m novas id\u00e9ias, levando em considera\u00e7\u00e3o a din\u00e2mica do comportamento humano, da cultura e do pensamento individual para responder a perguntas sobre conformidade social distanciadora ou o surgimento de comportamentos indesejados de grupo&#8221;, disse&nbsp;<a href=\"https:\/\/www.gartner.com\/analyst\/79613\">Pieter den Hamer<\/a>&nbsp;, diretor s\u00eanior de pesquisa da Gartner.&nbsp;&#8220;A aplica\u00e7\u00e3o da lei pode prever onde e quando as pessoas podem n\u00e3o aderir a ordens de permanecer em casa ou o distanciamento social por meio da aplica\u00e7\u00e3o preditiva e das unidades de aplica\u00e7\u00e3o da expedi\u00e7\u00e3o de acordo.&#8221; &nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Triagem e diagn\u00f3stico<\/h4>\n\n\n\n<p>O uso da auto-triagem habilitada para IA j\u00e1 ganhou popularidade. As pr\u00e1ticas de telessa\u00fade, incluindo assistentes virtuais de sa\u00fade, foram disponibilizadas para ajudar as pessoas a identificar se est\u00e3o possivelmente infectadas e quais s\u00e3o as pr\u00f3ximas etapas.&nbsp;O diagn\u00f3stico m\u00e9dico aumentado e a triagem tamb\u00e9m s\u00e3o os principais recursos de IA que ajudam nessa \u00e1rea.<\/p>\n\n\n\n<p>&#8220;A IA \u00e9 conhecida por melhorar a precis\u00e3o de certos diagn\u00f3sticos se aumentada com julgamento humano, especialmente em casos mais complexos&#8221;, disse den Hamer.&nbsp;\u201cA modelagem progn\u00f3stica ou a previs\u00e3o de como a doen\u00e7a provavelmente se desenvolver\u00e1 nos pacientes tamb\u00e9m podem ser usadas para melhorar as recomenda\u00e7\u00f5es de tratamento.&nbsp;O fato de a IA ter um papel a desempenhar na avalia\u00e7\u00e3o de risco e progn\u00f3stico do paciente n\u00e3o \u00e9 algo a ser esquecido, especialmente quando h\u00e1 uma poss\u00edvel escassez de profissionais m\u00e9dicos. \u201d&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Opera\u00e7\u00f5es de Sa\u00fade<\/h4>\n\n\n\n<p>A IA desempenha um papel importante na racionaliza\u00e7\u00e3o das opera\u00e7\u00f5es de assist\u00eancia m\u00e9dica. Al\u00e9m disso, tamb\u00e9m promove a otimiza\u00e7\u00e3o de recursos hospitalares escassos durante uma pandemia.&nbsp;Os&nbsp;<a href=\"https:\/\/www.gartner.com\/smarterwithgartner\/coronavirus-cio-areas-of-focus-during-the-covid-19-outbreak\/\">CIOs<\/a>&nbsp;e CDOs da \u00e1rea de&nbsp;sa\u00fade&nbsp;podem usar equipes preditivas para melhorar a aloca\u00e7\u00e3o de pessoal. Dessa forma, \u00e9 poss\u00edvel analisar os n\u00fameros previstos de pacientes e seu progn\u00f3stico individual e fazer refer\u00eancia cruzada com a disponibilidade de equipe m\u00e9dica, materiais e equipamentos qualificados.<\/p>\n\n\n\n<p>&#8220;O monitoramento remoto dos pacientes e o alerta com o uso da IA \u200b\u200btamb\u00e9m permitem que os pacientes fiquem em casa, diminuem a carga sobre os hospitais e permitem uma melhor compreens\u00e3o de como os sintomas se desenvolvem ao longo do tempo&#8221;, disse den Hamer.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Pesquisa e desenvolvimento de vacinas (P&amp;D)<\/h4>\n\n\n\n<p>Os gr\u00e1ficos de IA e&nbsp;<a href=\"https:\/\/www.gartner.com\/en\/information-technology\/glossary\/natural-language-processing-nlp\">o processamento em linguagem natural (PNL)<\/a>&nbsp;podem permitir que os pesquisadores m\u00e9dicos vasculhem milhares de relat\u00f3rios para estabelecer conex\u00f5es entre dados em um ritmo sem precedentes.&nbsp;A pesquisa e desenvolvimento de vacinas aumentadas tamb\u00e9m identificam contramedidas de coronav\u00edrus, incluindo aquelas que j\u00e1 foram testadas em seres humanos.<\/p>\n\n\n\n<p>\u201cOs CIOs e CDOs da \u00e1rea de sa\u00fade devem explorar todas as possibilidades de IA para combater o COVID-19 usando um processo cont\u00ednuo e sistem\u00e1tico de identifica\u00e7\u00e3o e prioriza\u00e7\u00e3o de aplicativos de IA.&nbsp;Os tecn\u00f3logos n\u00e3o devem superestimar sua capacidade de entender o que faz sentido do ponto de vista da sa\u00fade p\u00fablica e da medicina e, em seguida, trabalhar com profissionais de sa\u00fade para criar e anunciar ativamente um mercado aberto que compartilhe aplicativos, modelos e dados de IA de forma transparente \u201d, disse den Hamer.<\/p>\n\n\n\n<p>Fonte: Gartner Inc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa da Gartner Inc. apresentou as cinco \u00e1reas em que a Intelig\u00eancia Artificial mais beneficia e facilita as tomadas de decis\u00f5es para CIOs do Governo e da Sa\u00fade durante a pandemia. Segundo a an\u00e1lise, os recursos de IA s\u00e3o mais eficazes com a colabora\u00e7\u00e3o entre as equipes de TI e m\u00e9dicos especialistas em epidemias. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[680],"tags":[],"class_list":["post-1325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tech-trends"],"_links":{"self":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":0,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/media\/1339"}],"wp:attachment":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}