{"id":3387,"date":"2020-12-10T14:38:12","date_gmt":"2020-12-10T17:38:12","guid":{"rendered":"https:\/\/hdbsystems.com.br\/?p=3387"},"modified":"2020-12-10T14:38:12","modified_gmt":"2020-12-10T17:38:12","slug":"marketing-e-tecnologia-coworkers-inseparaveis","status":"publish","type":"post","link":"https:\/\/hdbsystems.com.br\/index.php\/2020\/12\/10\/marketing-e-tecnologia-coworkers-inseparaveis\/","title":{"rendered":"Marketing e tecnologia &#8211; coworkers insepar\u00e1veis"},"content":{"rendered":"\n<p>Ao longo do ano de 2020 a amizade entre as \u00e1reas de marketing e tecnologia se fortaleceu por conta da pandemia. Al\u00e9m disso, o document\u00e1rio que bombou no segundo semestre do ano, \u201cO Dilema das Redes\u201d, fez muitos perceberem o quanto o marketing e os processos de compra est\u00e3o estreitamente ligados \u00e0 tecnologia atrav\u00e9s dos <a href=\"https:\/\/hdbsystems.com.br\/index.php\/solucoes-na-nuvem\/\">dados<\/a>.<\/p>\n\n\n\n<p>A Gartner, Inc. e seus analistas exploraram as principais previs\u00f5es que definem como os profissionais de marketing devem redefinir e restabelecer o relacionamento com o cliente no \u00a0<a href=\"https:\/\/www.gartner.com\/en\/conferences\/na\/marketing-symposium-us\">Gartner Marketing Symposium \/ Xpo<\/a>. O evento ocorreu virtualmente nos dias de 1, 2 e 3 de dezembro revelou que as estrat\u00e9gias de renova\u00e7\u00e3o p\u00f3s-pandemia s\u00e3o necess\u00e1rias. O marketing precisa, atrav\u00e9s da tecnologia, redefinir e restabelecer relacionamentos com o cliente de acordo com o \u201cnovo normal\u201d digital.\u00a0<\/p>\n\n\n\n<p>\u201cA necessidade de vis\u00e3o, inova\u00e7\u00e3o e transforma\u00e7\u00e3o nunca foi t\u00e3o pronunciada para os profissionais de marketing\u201d, disse\u00a0<a href=\"https:\/\/www.gartner.com\/en\/experts\/jennifer-polk\">Jennifer Polk<\/a>\u00a0, analista vice-presidente da\u00a0<a href=\"https:\/\/www.gartner.com\/en\/marketing\">pr\u00e1tica de Marketing<\/a>\u00a0do\u00a0<a href=\"https:\/\/www.gartner.com\/en\/marketing\">Gartner<\/a>\u00a0.\u00a0\u201cOs profissionais de marketing precisam reinventar a forma como se relacionam com os clientes de hoje, usando canais online e offline para criar experi\u00eancias ricas, criativas e envolventes.\u201d, completa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Previs\u00f5es da alian\u00e7a marketing &amp; tecnologia<\/h4>\n\n\n\n<p>\u00c9 importante lembrar que, diante de uma pandemia global, as necessidades do cliente est\u00e3o sendo redefinidas. Segundo a pesquisa, em 2024, 30% das grandes organiza\u00e7\u00f5es identificar\u00e3o os servi\u00e7os de modera\u00e7\u00e3o de conte\u00fado para conte\u00fado gerado pelo usu\u00e1rio como uma prioridade do C-Suite (principais cargos e t\u00edtulos das empresas).<\/p>\n\n\n\n<p>As principais plataformas de redes sociais e varejistas que dependem do conte\u00fado gerado pelo usu\u00e1rio para impulsionar o engajamento e as vendas enfrentam uma enxurrada de conte\u00fado malicioso, que vai desde an\u00e1lises fraudulentas e listas de produtos at\u00e9 o compartilhamento equivocado de conte\u00fado falso ou n\u00e3o verificado.\u00a0A consequ\u00eancia disso \u00e9 um n\u00famero crescente de servi\u00e7os de modera\u00e7\u00e3o de conte\u00fado e provedores de tecnologia que entram no mercado.<\/p>\n\n\n\n<p>As organiza\u00e7\u00f5es devem combater a percep\u00e7\u00e3o negativa e os riscos \u00e0 reputa\u00e7\u00e3o que surgem quando os funcion\u00e1rios se manifestam.&nbsp;As organiza\u00e7\u00f5es precisar\u00e3o dedicar recursos para lidar com os coment\u00e1rios negativos dos funcion\u00e1rios e ficar a par das discrep\u00e2ncias entre o que os profissionais de marketing est\u00e3o dizendo e o que os funcion\u00e1rios est\u00e3o vivenciando.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Em 2023, 25% das organiza\u00e7\u00f5es unir\u00e3o marketing, vendas e CX em uma \u00fanica fun\u00e7\u00e3o.<\/h4>\n\n\n\n<p>Setenta e sete por cento dos l\u00edderes de marketing relatam que lutaram para acompanhar as mudan\u00e7as nas necessidades dos clientes e 87% acreditam que as mudan\u00e7as nas necessidades dos clientes se tornar\u00e3o ainda mais comuns nos pr\u00f3ximos anos.&nbsp;Isso obrigou muitas organiza\u00e7\u00f5es a buscar solu\u00e7\u00f5es colaborativas de longo prazo.&nbsp;<\/p>\n\n\n\n<p>Como resultado, a \u00e1rea de sobreposi\u00e7\u00e3o entre&nbsp;<a href=\"https:\/\/www.gartner.com\/en\/marketing\/insights\/customer-experience\">a experi\u00eancia do cliente<\/a>&nbsp;(CX) e as fun\u00e7\u00f5es de vendas e marketing est\u00e1 aumentando rapidamente.&nbsp;Enquanto a CX sempre se concentrou em construir uma compreens\u00e3o clara de quem \u00e9 o cliente e como as intera\u00e7\u00f5es com a marca agregam ou diminuem valor ao longo de sua vida, as vendas e o marketing tamb\u00e9m est\u00e3o agora focados nesse objetivo.&nbsp;As organiza\u00e7\u00f5es ir\u00e3o combinar formalmente vendas e marketing e CX sob um \u00fanico l\u00edder com responsabilidade clara e inequ\u00edvoca para manter e aumentar o valor vital\u00edcio do cliente e a lucratividade.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Em 2023, 60% das empresas voltadas para e-commerce ir\u00e3o incorporar elementos experienciais em tempo real \/ espa\u00e7o real.\u00a0<\/h4>\n\n\n\n<p>Os consumidores demonstraram a rapidez com que podem mudar seu comportamento para novas tecnologias e canais com a pandemia COVID-19.\u00a0Os clientes B2C e B2B n\u00e3o est\u00e3o mudando do anal\u00f3gico para o digital, eles est\u00e3o mudando de um bin\u00e1rio digital-anal\u00f3gico para experi\u00eancias de modo h\u00edbrido \/ misto.\u00a0Por isso, n\u00e3o \u00e9 poss\u00edvel que cada vez cres\u00e7a cada vez mais o n\u00famero de aplicativos de realidade aumentada. Assim, eles oferecer\u00e3o experi\u00eancias mais reais ainda que digitais, como pop-ups drive-through e experi\u00eancias sensoriais digitais exclusivas.\u00a0<\/p>\n\n\n\n<p>No entanto, nem todas as empresas possuem estruturas organizacionais de marketing adequadas para isso. Na verdade, apenas 30% das marcas B2C relatam ter esse alinhamento organizacional funcional.\u00a0As marcas que definem seus planos futuros para o e-commerce &#8211; e estruturam equipes de acordo &#8211; devem pensar duas vezes.\u00a0As marcas devem aproveitar esse tempo para reorientar equipes e objetivos em torno de uma estrat\u00e9gia agn\u00f3stica de canal em primeiro lugar.<\/p>\n\n\n\n<p>Atrav\u00e9s dessas predi\u00e7\u00f5es conseguimos perceber com mais clareza como o document\u00e1rio mencionado no in\u00edcio do texto \u00e9 real. A tecnologia que utiliza a intelig\u00eancia artificial para extrair informa\u00e7\u00f5es atrav\u00e9s de dados molda a forma como consumimos e o que consumimos. Pode parecer muito injusto por\u00e9m, \u00e9 importante lembrar que essa mesma tecnologia \u00e9 o que nos permite ter acesso a determinadas coisas que, em um momento pand\u00eamico como esse, n\u00e3o seriam poss\u00edveis sem ela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao longo do ano de 2020 a amizade entre as \u00e1reas de marketing e tecnologia se fortaleceu por conta da pandemia. Al\u00e9m disso, o document\u00e1rio que bombou no segundo semestre do ano, \u201cO Dilema das Redes\u201d, fez muitos perceberem o quanto o marketing e os processos de compra est\u00e3o estreitamente ligados \u00e0 tecnologia atrav\u00e9s dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[674],"tags":[807,808,809,810,772,811,729],"class_list":["post-3387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rpa","tag-analisededados","tag-dados","tag-data","tag-dilemadasredes","tag-inteligenciaartificial-3","tag-marketing","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3387"}],"version-history":[{"count":0,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/media\/3390"}],"wp:attachment":[{"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hdbsystems.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}